{"id":783,"date":"2021-02-05T14:43:20","date_gmt":"2021-02-05T19:43:20","guid":{"rendered":"https:\/\/forms.hope.edu\/engagement\/?page_id=783"},"modified":"2023-04-20T13:49:13","modified_gmt":"2023-04-20T17:49:13","slug":"alumni-board-nomination","status":"publish","type":"page","link":"https:\/\/forms.hope.edu\/engagement\/alumni-board-nomination\/","title":{"rendered":"Alumni Board Nomination"},"content":{"rendered":"<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_114' style='display:none'>\n                        <div class='gform_heading'>\n                            <p class='gform_description'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_114'  action='\/engagement\/wp-json\/wp\/v2\/pages\/783' data-formid='114' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_114' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_114_16\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_16'>Phone<\/label><div class='ginput_container'><input name='input_16' id='input_114_16' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_114_16'>This field is for validation purposes and should be left unchanged.<\/div><\/div><fieldset id=\"field_114_1\" class=\"gfield gfield--type-radio gfield--type-choice gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label' >Who are you Nominating?<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_container ginput_container_radio'><div class='gfield_radio' id='input_114_1'>\n\t\t\t<div class='gchoice gchoice_114_1_0'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_1' type='radio' value='Myself'  id='choice_114_1_0' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_114_1_0' id='label_114_1_0' class='gform-field-label gform-field-label--type-inline'>Myself<\/label>\n\t\t\t<\/div>\n\t\t\t<div class='gchoice gchoice_114_1_1'>\n\t\t\t\t\t<input class='gfield-choice-input' name='input_1' type='radio' value='Someone Else'  id='choice_114_1_1' onchange='gformToggleRadioOther( this )'    \/>\n\t\t\t\t\t<label for='choice_114_1_1' id='label_114_1_1' class='gform-field-label gform-field-label--type-inline'>Someone Else<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><fieldset id=\"field_114_3\" class=\"gfield gfield--type-name gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_114_3'>\n                            \n                            <span id='input_114_3_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_3.3' id='input_114_3_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_3_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_114_3_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_3.6' id='input_114_3_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_3_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_114_4\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_4'>Class Year<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_4' id='input_114_4' class='small gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='2022' >2022<\/option><option value='2021' >2021<\/option><option value='2020' >2020<\/option><option value='2019' >2019<\/option><option value='2018' >2018<\/option><option value='2017' >2017<\/option><option value='2016' >2016<\/option><option value='2015' >2015<\/option><option value='2014' >2014<\/option><option value='2013' >2013<\/option><option value='2012' >2012<\/option><option value='2011' >2011<\/option><option value='2010' >2010<\/option><option value='2009' >2009<\/option><option value='2008' >2008<\/option><option value='2007' >2007<\/option><option value='2006' >2006<\/option><option value='2005' >2005<\/option><option value='2004' >2004<\/option><option value='2003' >2003<\/option><option value='2002' >2002<\/option><option value='2001' >2001<\/option><option value='2000' >2000<\/option><option value='1999' >1999<\/option><option value='1998' >1998<\/option><option value='1997' >1997<\/option><option value='1996' >1996<\/option><option value='1995' >1995<\/option><option value='1994' >1994<\/option><option value='1993' >1993<\/option><option value='1992' >1992<\/option><option value='1991' >1991<\/option><option value='1990' >1990<\/option><option value='1989' >1989<\/option><option value='1988' >1988<\/option><option value='1987' >1987<\/option><option value='1986' >1986<\/option><option value='1985' >1985<\/option><option value='1984' >1984<\/option><option value='1983' >1983<\/option><option value='1982' >1982<\/option><option value='1981' >1981<\/option><option value='1980' >1980<\/option><option value='1979' >1979<\/option><option value='1978' >1978<\/option><option value='1977' >1977<\/option><option value='1976' >1976<\/option><option value='1975' >1975<\/option><option value='1974' >1974<\/option><option value='1973' >1973<\/option><option value='1972' >1972<\/option><option value='1971' >1971<\/option><option value='1970' >1970<\/option><option value='1969' >1969<\/option><option value='1968' >1968<\/option><option value='1967' >1967<\/option><option value='1966' >1966<\/option><option value='1965' >1965<\/option><option value='1964' >1964<\/option><option value='1963' >1963<\/option><option value='1962' >1962<\/option><option value='1961' >1961<\/option><option value='1960' >1960<\/option><option value='1959' >1959<\/option><option value='1958' >1958<\/option><option value='1957' >1957<\/option><option value='1956' >1956<\/option><option value='1955' >1955<\/option><option value='1954' >1954<\/option><option value='1953' >1953<\/option><option value='1952' >1952<\/option><option value='1951' >1951<\/option><option value='1950' >1950<\/option><option value='1949' >1949<\/option><option value='1948' >1948<\/option><option value='1947' >1947<\/option><option value='1946' >1946<\/option><option value='1945' >1945<\/option><option value='1944' >1944<\/option><option value='1943' >1943<\/option><option value='1942' >1942<\/option><option value='1941' >1941<\/option><option value='1940' >1940<\/option><option value='' ><\/option><\/select><\/div><\/div><div id=\"field_114_5\" class=\"gfield gfield--type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_5'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_5' id='input_114_5' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_114_6\" class=\"gfield gfield--type-phone gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_6'>Phone<\/label><div class='ginput_container ginput_container_phone'><input name='input_6' id='input_114_6' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_114_7\" class=\"gfield gfield--type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_7'>Reason for interest in Alumni Board membership<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_7' id='input_114_7' class='textarea large'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_114_8\" class=\"gfield gfield--type-name gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Your Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_114_8'>\n                            \n                            <span id='input_114_8_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_8.3' id='input_114_8_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_8_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_114_8_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_8.6' id='input_114_8_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_8_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_114_9\" class=\"gfield gfield--type-text gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_9'>Your Affiliation to Hope<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_9' id='input_114_9' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_114_10\" class=\"gfield gfield--type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_10'>Your Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_10' id='input_114_10' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_114_11\" class=\"gfield gfield--type-section gsection field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><h3 class=\"gsection_title\"><\/h3><\/div><fieldset id=\"field_114_12\" class=\"gfield gfield--type-name gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Nominee Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_complex ginput_container ginput_container--name no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name gform-grid-row' id='input_114_12'>\n                            \n                            <span id='input_114_12_3_container' class='name_first gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_12.3' id='input_114_12_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_12_3' class='gform-field-label gform-field-label--type-sub '>First<\/label>\n                                                <\/span>\n                            \n                            <span id='input_114_12_6_container' class='name_last gform-grid-col gform-grid-col--size-auto' >\n                                                    <input type='text' name='input_12.6' id='input_114_12_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_114_12_6' class='gform-field-label gform-field-label--type-sub '>Last<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_114_13\" class=\"gfield gfield--type-select gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_13'>Nominee Class Year<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_select'><select name='input_13' id='input_114_13' class='small gfield_select'    aria-required=\"true\" aria-invalid=\"false\" ><option value='2022' >2022<\/option><option value='2021' >2021<\/option><option value='2020' >2020<\/option><option value='2019' >2019<\/option><option value='2018' >2018<\/option><option value='2017' >2017<\/option><option value='2016' >2016<\/option><option value='2015' >2015<\/option><option value='2014' >2014<\/option><option value='2013' >2013<\/option><option value='2012' >2012<\/option><option value='2011' >2011<\/option><option value='2010' >2010<\/option><option value='2009' >2009<\/option><option value='2008' >2008<\/option><option value='2007' >2007<\/option><option value='2006' >2006<\/option><option value='2005' >2005<\/option><option value='2004' >2004<\/option><option value='2003' >2003<\/option><option value='2002' >2002<\/option><option value='2001' >2001<\/option><option value='2000' >2000<\/option><option value='1999' >1999<\/option><option value='1998' >1998<\/option><option value='1997' >1997<\/option><option value='1996' >1996<\/option><option value='1995' >1995<\/option><option value='1994' >1994<\/option><option value='1993' >1993<\/option><option value='1992' >1992<\/option><option value='1991' >1991<\/option><option value='1990' >1990<\/option><option value='1989' >1989<\/option><option value='1988' >1988<\/option><option value='1987' >1987<\/option><option value='1986' >1986<\/option><option value='1985' >1985<\/option><option value='1984' >1984<\/option><option value='1983' >1983<\/option><option value='1982' >1982<\/option><option value='1981' >1981<\/option><option value='1980' >1980<\/option><option value='1979' >1979<\/option><option value='1978' >1978<\/option><option value='1977' >1977<\/option><option value='1976' >1976<\/option><option value='1975' >1975<\/option><option value='1974' >1974<\/option><option value='1973' >1973<\/option><option value='1972' >1972<\/option><option value='1971' >1971<\/option><option value='1970' >1970<\/option><option value='1969' >1969<\/option><option value='1968' >1968<\/option><option value='1967' >1967<\/option><option value='1966' >1966<\/option><option value='1965' >1965<\/option><option value='1964' >1964<\/option><option value='1963' >1963<\/option><option value='1962' >1962<\/option><option value='1961' >1961<\/option><option value='1960' >1960<\/option><option value='1959' >1959<\/option><option value='1958' >1958<\/option><option value='1957' >1957<\/option><option value='1956' >1956<\/option><option value='1955' >1955<\/option><option value='1954' >1954<\/option><option value='1953' >1953<\/option><option value='1952' >1952<\/option><option value='1951' >1951<\/option><option value='1950' >1950<\/option><option value='1949' >1949<\/option><option value='1948' >1948<\/option><option value='1947' >1947<\/option><option value='1946' >1946<\/option><option value='1945' >1945<\/option><option value='1944' >1944<\/option><option value='1943' >1943<\/option><option value='1942' >1942<\/option><option value='1941' >1941<\/option><option value='1940' >1940<\/option><option value='' ><\/option><\/select><\/div><\/div><div id=\"field_114_14\" class=\"gfield gfield--type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_14'>Nominee Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_14' id='input_114_14' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_114_15\" class=\"gfield gfield--type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_114_15'>Reason for Nomination<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_15' id='input_114_15' class='textarea large'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_114' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_114' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_114' id='gform_theme_114' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_114' id='gform_style_settings_114' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_114' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='114' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='pNA0elR2uRiR1HiVkQGg21DC57DRvZAE7cBmhcNPrYcEvTs7s78SHMe0wiEhPwaoXLAoi1M3DzK3wCelkEBbOlauNGJ+eyAqsDJXfSN+vJW3zfE=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_114' value='WyJ7XCIxXCI6W1wiOThhZDJmMjVmZGI2OTY3OWM0Njk5MGQ2ZTBiYTEyYTJcIixcIjc2Y2RlYTk1YWVmOTE2MTFlYTFiMTgyOGJhYTg0MDUwXCJdfSIsIjY2MjliZmE2MThiNGE4YjhlYTliZTUxNmUyZDMxNDkzIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_114' id='gform_target_page_number_114' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_114' id='gform_source_page_number_114' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"25\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 114, 'https:\/\/forms.hope.edu\/engagement\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_114').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_114');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_114').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){form_content.find('form').css('opacity', 0);jQuery('#gform_wrapper_114').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_114').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_114').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_114').val();gformInitSpinner( 114, 'https:\/\/forms.hope.edu\/engagement\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [114, current_page]);window['gf_submitting_114'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_114').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [114]);window['gf_submitting_114'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_114').text());}else{jQuery('#gform_114').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"114\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_114\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_114\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_114\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 114, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-783","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/pages\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":5,"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/pages\/783\/revisions"}],"predecessor-version":[{"id":1017,"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/pages\/783\/revisions\/1017"}],"wp:attachment":[{"href":"https:\/\/forms.hope.edu\/engagement\/wp-json\/wp\/v2\/media?parent=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}